{"id":97,"count":17,"description":"","link":"https:\/\/attapoll.com\/en-ca\/category\/uncategorised\/","name":"Uncategorized","slug":"uncategorised","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/attapoll.com\/en-ca\/wp-json\/wp\/v2\/categories\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/attapoll.com\/en-ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/attapoll.com\/en-ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/attapoll.com\/en-ca\/wp-json\/wp\/v2\/posts?categories=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}